{"id":474,"date":"2017-05-13T09:02:46","date_gmt":"2017-05-13T09:02:46","guid":{"rendered":"https:\/\/playgroundenterprice.com.ec\/home_pc\/standard-2-columns-grid\/"},"modified":"2019-05-27T01:20:35","modified_gmt":"2019-05-27T01:20:35","slug":"portafolio","status":"publish","type":"page","link":"https:\/\/plasticloset.com\/home_pc\/portafolio\/","title":{"rendered":"Portafolio"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]<a href=\"https:\/\/plasticloset.com\/home_pc\/catalogo_plastiwindoor.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4058 size-full\" src=\"https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/ver-CATALOGO.png\" alt=\"\" width=\"1760\" height=\"178\" srcset=\"https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/ver-CATALOGO.png 1760w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/ver-CATALOGO-300x30.png 300w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/ver-CATALOGO-768x78.png 768w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/ver-CATALOGO-1024x104.png 1024w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/ver-CATALOGO-600x61.png 600w\" sizes=\"auto, (max-width: 1760px) 100vw, 1760px\" \/><\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text]\n<p class=\"vp-img-paragraph\"><a class=\"vp-a vp-yt-type\" href=\"https:\/\/www.youtube.com\/watch?v=iUIefafgfyc\" data-autoplay=\"1\" data-ytid=\"iUIefafgfyc\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4020 size-full\" src=\"https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia.png\" alt=\"\" width=\"1897\" height=\"1078\" srcset=\"https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia.png 1897w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-300x170.png 300w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-768x436.png 768w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-1024x582.png 1024w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-600x341.png 600w\" sizes=\"auto, (max-width: 1897px) 100vw, 1897px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_column_text]\n<p class=\"vp-img-paragraph\"><a class=\"vp-a vp-yt-type\" href=\"https:\/\/www.youtube.com\/watch?v=WPhAei_Ehyk\" data-autoplay=\"1\" data-ytid=\"WPhAei_Ehyk\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4022 size-full\" src=\"https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-2.png\" alt=\"\" width=\"1897\" height=\"1079\" srcset=\"https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-2.png 1897w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-2-300x171.png 300w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-2-768x437.png 768w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-2-1024x582.png 1024w, https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/videos_Mesa-de-trabajo-50-copia-2-600x341.png 600w\" sizes=\"auto, (max-width: 1897px) 100vw, 1897px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<section id='cwsportfolio_posts_grid_6a5793f2c3f47' class='posts_grid cwsportfolio_posts_grid posts_grid_2 posts_grid_filter dynamic_content simple_filter start_even carousel_nav render_styles ' data-style='&quot;&quot;' data-col='2'><ul class='filter_wrap'><li data-filter='_all_' class='filter active'>All<\/li><li data-filter='gallery' class='filter'>Gallery<\/li><li data-filter='plastiwindoor' class='filter'>Plastiwindoor<\/li><\/ul><select class='filter'><option value='_all_' selected>All<\/option><option value='gallery'>Gallery<\/option><option value='plastiwindoor'>Plastiwindoor<\/option><\/select><div class='loft_wrapper'><div class='loft_grid isotope carousel_nav'><article id='post_post_4085' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-66_025801530.png' data-no-retina alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-5-2\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-5-2\/'>Gallery 5<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/gallery\/'>Gallery<\/a><\/div><\/div><\/article><article id='post_post_4083' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-65_025801540.png' data-at2x='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-65_025801540@2x.png' alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-4-2\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-4-2\/'>Gallery 4<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/gallery\/'>Gallery<\/a><\/div><\/div><\/article><article id='post_post_4081' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-64_025801540.png' data-at2x='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-64_025801540@2x.png' alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-3\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-3\/'>Gallery 3<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/gallery\/'>Gallery<\/a><\/div><\/div><\/article><article id='post_post_4079' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-62_025801530.png' data-at2x='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-62_025801530@2x.png' alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-2-2\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-2-2\/'>Gallery 2<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/gallery\/'>Gallery<\/a><\/div><\/div><\/article><article id='post_post_4077' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-61_025801520.png' data-at2x='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Gallery-Port-61_025801520@2x.png' alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-1-2\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/gallery-1-2\/'>SALAS<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/gallery\/'>Gallery<\/a><\/div><\/div><\/article><article id='post_post_4075' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Plastiwindoor-Portf-61_025801520.png' data-no-retina alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/pw6\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/pw6\/'>PW6<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/plastiwindoor\/'>Plastiwindoor<\/a><\/div><\/div><\/article><article id='post_post_4071' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Plastiwindoor-Portf-60_025801530.png' data-at2x='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Plastiwindoor-Portf-60_025801530@2x.png' alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/pw-5\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/pw-5\/'>PW 5<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/plastiwindoor\/'>Plastiwindoor<\/a><\/div><\/div><\/article><article id='post_post_4069' class='item portfolio_item_post portfolio_item_grid_post clearfix under_img appear_style hoverdef'   ><div class='item_content'><div class='post_media post_post_media post_posts_grid_post_media'><div class=' pic'><img src='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Plastiwindoor-Portf-59_025801520.png' data-at2x='https:\/\/plasticloset.com\/home_pc\/wp-content\/uploads\/2019\/04\/Plastiwindoor-Portf-59_025801520@2x.png' alt \/><\/div><div class='cwsportfolio_content_wrap'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/pw-4\/' class='links area'><\/a><div class='hover-effect'><\/div><\/div><\/div><h3 class='cwsportfolio_post_title post_title text_alignright'><a href='https:\/\/plasticloset.com\/home_pc\/portfolio\/pw-4\/'>pw 4<\/a><\/h3><div class='cwsportfolio_post_terms post_terms text_alignright'>&#x20;<a href='https:\/\/plasticloset.com\/home_pc\/portfolio-cat\/plastiwindoor\/'>Plastiwindoor<\/a><\/div><\/div><\/article><\/div><div  class='cws_loader_holder'><div  class='cws_loader'>\t\t\t<svg width='104px' height='104px' xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\" preserveAspectRatio=\"xMidYMid\" class=\"uil-default\"><rect x=\"0\" y=\"0\" width=\"100\" height=\"100\" fill=\"none\" class=\"bk\"><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(0 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(30 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.08333333333333333s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(60 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.16666666666666666s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(90 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.25s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(120 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.3333333333333333s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(150 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.4166666666666667s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(180 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.5s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(210 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.5833333333333334s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(240 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.6666666666666666s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(270 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.75s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(300 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.8333333333333334s' repeatCount='indefinite'\/><\/rect><rect  x='46.5' y='40' width='7' height='20' rx='5' ry='5' fill='#000000' transform='rotate(330 50 50) translate(0 -30)'>  <animate attributeName='opacity' from='1' to='0' dur='1s' begin='0.9166666666666666s' repeatCount='indefinite'\/><\/rect><\/svg>\r\n\t\t\t<\/div><\/div><\/div>\t\t<a class=\"loft_button mini loft_load_more\" href=\"#\">Load More<\/a>\r\n\t<form id='cwsportfolio_posts_grid_6a5793f2c3f47_data' class='posts_grid_data'><input type='hidden' id='cwsportfolio_posts_grid_6a5793f2c3f47_ajax_data' class='posts_grid_ajax_data' name='cwsportfolio_posts_grid_6a5793f2c3f47_ajax_data' value='{\"section_id\":\"cwsportfolio_posts_grid_6a5793f2c3f47\",\"post_type\":\"cwsportfolio\",\"cwsportfolio_data_to_show\":[\"!!!dummy!!!\",\"title\",\"cats\"],\"link_show\":[\"area_link\"],\"layout\":\"2\",\"hex_layout\":\"4\",\"hex_w\":\"\",\"hex_h\":\"\",\"start_style\":\"start_even\",\"sort_by\":\"date\",\"sorting\":\"DESC\",\"display_style\":\"filter\",\"hex_display_style\":\"grid\",\"sb_layout\":\"\",\"total_items_count\":20,\"full_width\":false,\"items_pp\":8,\"page\":1,\"max_paged\":2,\"tax\":\"cwsportfolio-cat\",\"terms\":[\"gallery\",\"plastiwindoor\"],\"filter\":true,\"current_filter_val\":\"_all_\",\"addl_query_args\":[],\"portfolio_style\":\"\",\"info_pos\":\"under_img\",\"masonry\":false,\"anim_style\":\"hoverdef\",\"item_shadow\":false,\"appear_style\":\"none\",\"isotope_line_count\":\"\",\"isotope_col_count\":\"\",\"chars_count\":\"\",\"info_align\":\"right\",\"pag_type\":\"load_pag\"}' \/><\/form><\/section>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_column_text] [\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-474","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/pages\/474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/comments?post=474"}],"version-history":[{"count":6,"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/pages\/474\/revisions"}],"predecessor-version":[{"id":4060,"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/pages\/474\/revisions\/4060"}],"wp:attachment":[{"href":"https:\/\/plasticloset.com\/home_pc\/wp-json\/wp\/v2\/media?parent=474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}